{"id":9874,"date":"2017-12-09T19:20:32","date_gmt":"2017-12-09T18:20:32","guid":{"rendered":"http:\/\/djalil.chafai.net\/blog\/?p=9874"},"modified":"2024-03-02T16:59:16","modified_gmt":"2024-03-02T15:59:16","slug":"mega","status":"publish","type":"post","link":"https:\/\/djalil.chafai.net\/blog\/2017\/12\/09\/mega\/","title":{"rendered":"MEGA"},"content":{"rendered":"<figure id=\"attachment_9876\" aria-describedby=\"caption-attachment-9876\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"size-medium wp-image-9876\" src=\"http:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2017\/12\/Yan-Fyodorov-MEGA-IHP-2017-12-08-300x293.png\" alt=\"MEGA seminar at IHP.\" width=\"300\" height=\"293\" srcset=\"https:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2017\/12\/Yan-Fyodorov-MEGA-IHP-2017-12-08-300x293.png 300w, https:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2017\/12\/Yan-Fyodorov-MEGA-IHP-2017-12-08-150x146.png 150w, https:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2017\/12\/Yan-Fyodorov-MEGA-IHP-2017-12-08.png 381w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-9876\" class=\"wp-caption-text\">Yan Fyodorov lors du MEGA \u00e0 l'IHP. Sur le tableau la subsistance du N apr\u00e8s le passage \u00e0 la limite \ud83d\ude42<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">J'\u00e9tais vendredi \u00e0 l'<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Institut_Henri-Poincar%C3%A9\">Institut Henri-Poincar\u00e9<\/a>\u00a0 pour les expos\u00e9s mensuel du <a href=\"http:\/\/djalil.chafai.net\/wiki\/mega:start\">MEGA<\/a>\u00a0(Matrices Et Graphes Al\u00e9atoires). Saviez-vous que cet institut doit son existence notamment aux efforts de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/%C3%89mile_Borel\">\u00c9mile Borel<\/a>\u00a0- math\u00e9maticien et homme politique, figure sans doute tr\u00e8s inspirante pour <a href=\"https:\/\/fr.wikipedia.org\/wiki\/C%C3%A9dric_Villani\">C\u00e9dric Villani<\/a> - ainsi qu'aux moyens de la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Fondation_Rockefeller\">Fondation Rockefeller<\/a> et de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Edmond_de_Rothschild\">Edmond de Rothschild<\/a> ?<\/p>\n<p style=\"text-align: justify;\">Le cours didactique du matin \u00e9tait donn\u00e9 par <a href=\"http:\/\/www.normalesup.org\/~menard\/\">Laurent M\u00e9nard<\/a>, et portait sur la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Combinatoire_analytique\">combinatoire analytique<\/a>\u00a0\u00e0 la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Philippe_Flajolet\">Philippe Flajolet<\/a>. Il s'agit typiquement d'obtenir des formules de comptage notamment asymptotiques en utilisant l'arsenal de l'analyse complexe (int\u00e9grales de contour, m\u00e9thode du col, ...) \u00e0 partir d'identit\u00e9s combinatoires fonctionnelles sur les fonctions g\u00e9n\u00e9ratrices. D'apr\u00e8s Laurent, une excellente r\u00e9f\u00e9rence est le livre <a href=\"http:\/\/algo.inria.fr\/flajolet\/Publications\/book.pdf\">Analytic combinatorics<\/a>.<\/p>\n<p style=\"text-align: justify;\">Le premier expos\u00e9 de l'apr\u00e8s-midi \u00e9tait donn\u00e9 par l'\u00e9nergique\u00a0<a href=\"https:\/\/www.kcl.ac.uk\/nms\/depts\/mathematics\/people\/atoz\/Fyodorovy.aspx\">Yan Fyodorov<\/a> et portait sur l'article\u00a0<a href=\"https:\/\/arxiv.org\/abs\/1710.04699\">arXiv:1710.04699<\/a>\u00a0concernant des formules explicites pour des statistiques li\u00e9es aux vecteurs propres pour les mod\u00e8les matriciels gaussiens de Ginibre r\u00e9el et complexe. Le second \u00e9tait donn\u00e9 par <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Alice_Guionnet\">Alice Guionnet<\/a> et portait sur l'\u00e9tude de mod\u00e8les de gaz discrets avec beta variable, en liaison par exemple avec l'article\u00a0<a href=\"https:\/\/arxiv.org\/abs\/1705.05527\">arXiv:1705.05527<\/a>. Dans les deux cas, la virtuosit\u00e9 et l'arsenal techniques sont impressionnants. Ces deux orateurs sont des sommit\u00e9s mondiales.<\/p>\n<p style=\"text-align: justify;\">Il semble que dans le domaine des matrices al\u00e9atoires, la plupart des questions simples abordables ont d\u00e9j\u00e0 \u00e9t\u00e9 explor\u00e9es. Doit-on s'attendre dans le futur \u00e0 des vagues de travaux simplificateurs ? C'est ce qu'on peut souhaiter au sujet. Certains pensent que pour survivre au temps, les math\u00e9matiques ont besoin d'\u00eatre simples et profondes et que cela r\u00e9sulte d'une lente digestion collective. Au del\u00e0 de ce domaine, il est frappant de constater la place grandissante de la sophistication technique dans les math\u00e9matiques actuelles. On se prend \u00e0 douter parfois.<\/p>\n<p style=\"text-align: justify;\">En tout cas, ces trois expos\u00e9s \u00e9taient passionnants et enthousiasmants !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J'&eacute;tais vendredi &agrave; l'Institut Henri-Poincar&eacute;&nbsp; pour les expos&eacute;s mensuel du MEGA&nbsp;(Matrices Et Graphes Al&eacute;atoires). Saviez-vous que cet institut doit son existence notamment aux efforts de&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/djalil.chafai.net\/blog\/2017\/12\/09\/mega\/\">Continue reading<span class=\"screen-reader-text\">MEGA<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":96},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts\/9874"}],"collection":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/comments?post=9874"}],"version-history":[{"count":30,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts\/9874\/revisions"}],"predecessor-version":[{"id":19464,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts\/9874\/revisions\/19464"}],"wp:attachment":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/media?parent=9874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/categories?post=9874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/tags?post=9874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}