{"id":9043,"date":"2016-10-19T19:07:10","date_gmt":"2016-10-19T17:07:10","guid":{"rendered":"http:\/\/djalil.chafai.net\/blog\/?p=9043"},"modified":"2020-03-08T11:29:15","modified_gmt":"2020-03-08T10:29:15","slug":"reflexions-sur-les-frais-dinscription-en-licence-a-luniversite","status":"publish","type":"post","link":"https:\/\/djalil.chafai.net\/blog\/2016\/10\/19\/reflexions-sur-les-frais-dinscription-en-licence-a-luniversite\/","title":{"rendered":"R\u00e9flexions sur les frais d'inscription en licence \u00e0 l'universit\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-6260\" src=\"http:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2013\/07\/Universit\u00e9_Paris-Dauphine.png\" alt=\"Universit\u00e9_Paris-Dauphine\" width=\"259\" height=\"102\" \/><\/p>\n<p style=\"text-align: justify;\">Ce petit billet regroupe quelques libres pens\u00e9es personnelles \u00e9parses sur les droits ou frais d'inscription en licence \u00e0 l'universit\u00e9 en France. En France, le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Licence_%28France%29\">dipl\u00f4me de licence<\/a> est national, et sa d\u00e9livrance est soumise \u00e0 un certain nombre de contraintes, comme par exemple l'absence de s\u00e9lection \u00e0 l'inscription ainsi que le respect de frais d'<a href=\"http:\/\/www.enseignementsup-recherche.gouv.fr\/cid20195\/frais-d-inscription-pour-la-rentree-universitaire-2016.html\">inscription nationaux fix\u00e9s par l'\u00e9tat<\/a>. Une inscription en ann\u00e9e de licence co\u00fbte actuellement 184 \u20ac, et seulement 12 \u20ac pour les boursiers.<\/p>\n<p style=\"text-align: justify;\">On a coutume de dire de mani\u00e8re g\u00e9n\u00e9rale que faire payer \u00e0 tout le monde le m\u00eame prix est plut\u00f4t de droite, tandis que moduler le prix en fonction du revenu est plut\u00f4t de gauche. De ce point de vue, la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Taxe_sur_la_valeur_ajout%C3%A9e\">TVA<\/a> est plut\u00f4t un imp\u00f4t de droite, tandis que la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Contribution_sociale_g%C3%A9n%C3%A9ralis%C3%A9e\">CSG<\/a> est plut\u00f4t un imp\u00f4t de gauche. Le prix de beaucoup de biens et de services est modul\u00e9 en fonction du revenu, de mani\u00e8re plus ou moins fine : cantines scolaires, \u00e9quipements sportifs, transports, etc. Les frais d'inscription de licence, qui sont modul\u00e9s de mani\u00e8re binaire selon que l'\u00e9tudiant est boursier ou non, sont plus de droite que de gauche, et ne permettent pas vraiment de redistribution locale au niveau de l'universit\u00e9.<\/p>\n<p style=\"text-align: justify;\">Un id\u00e9al de gauche voudrait que les imp\u00f4ts soient collect\u00e9s globalement par l'\u00e9tat, que la redistribution soit globale plut\u00f4t que locale, et que l'\u00e9ducation soit gratuite, y compris \u00e0 l'universit\u00e9, ce qui donnerait des frais d'inscription nuls. On peut consid\u00e9rer que les 184 \u20ac actuels sont proches de z\u00e9ro et que nous ne sommes donc pas loin de l'id\u00e9al. La r\u00e9alit\u00e9 est plus sombre. Depuis plusieurs dizaines d'ann\u00e9es, les standards internationaux lib\u00e9raux mettent sous pression les \u00e9tats, et ces derniers rechignent de plus en plus \u00e0 collecter l'imp\u00f4t globalement. La France ne fait pas exception et la dotation des universit\u00e9s en p\u00e2tit alors m\u00eame que les d\u00e9penses augmentent. Or les frais d'inscription des dipl\u00f4mes nationaux sont fix\u00e9s par l'\u00e9tat. L'\u00e9tat ne souhaite pas s'en servir comme variable d'ajustement, par d\u00e9magogie et peur du co\u00fbt politique des manifestations \u00e9tudiantes. Les universit\u00e9s ici et l\u00e0 ont donc recours \u00e0 des m\u00e9thodes d\u00e9tourn\u00e9es, comme par exemple la cr\u00e9ation de dipl\u00f4mes sp\u00e9ciaux contournant le dispositif national, avec des frais plus \u00e9lev\u00e9s. Il est peu probable qu'un gouvernement ose augmenter franchement les imp\u00f4ts globaux et\/ou instaurer une modulation des frais d'inscription. Il est probable que ce blocage perdure et provoque m\u00e9caniquement une lente d\u00e9gradation des conditions de travail et d'\u00e9tude dans les universit\u00e9s.<\/p>\n<p style=\"text-align: justify;\">\u00c9tant donn\u00e9e la situation de l'\u00e9tat et son caract\u00e8re probablement durable, des frais d'inscription modul\u00e9s en fonction du revenu seraient plus vertueux que le syst\u00e8me binaire fixe actuel et permettraient au passage une redistribution dans les universit\u00e9s qui accueillent \u00e0 la fois des \u00e9tudiants riches et des \u00e9tudiants pauvres (cela varie beaucoup en fonction de la discipline et de la position g\u00e9ographique). Il est toutefois peu probable que cela soit fait dans un avenir proche.<\/p>\n<p style=\"text-align: justify;\">La situation \u00e0 l'universit\u00e9 Paris-Dauphine est sp\u00e9cifique \u00e0 plus d'un titre. Le dipl\u00f4me national a \u00e9t\u00e9 abandonn\u00e9 au profit d'un dipl\u00f4me d'\u00e9tablissement qui a grade de licence, afin de se lib\u00e9rer \u00e0 la fois de la contrainte d'absence de s\u00e9lection et de la contrainte des frais d'inscription fix\u00e9s par l'\u00e9tat. Le d\u00e9partement d'informatique et de math\u00e9matiques de la d\u00e9cision et des organisations (MIDO) pratique actuellement les tarifs suivants pour les frais d'inscription en licence, hors boursiers : 530 \u20ac pour les deux premi\u00e8res ann\u00e9es et 184 \u20ac pour la troisi\u00e8me ann\u00e9e. D'un autre c\u00f4t\u00e9, le d\u00e9partement de licence en sciences des organisations (LSO) vient de mettre en place une modulation des frais d'inscription en licence en fonction du revenu, qui fait qu'un nombre non n\u00e9gligeable d'\u00e9tudiants payent moins qu'avant tandis que la somme totale r\u00e9colt\u00e9e a doubl\u00e9. Cette modulation n'est donc pas du tout synonyme d'augmentation des frais pour tous les \u00e9tudiants : cela d\u00e9pend du revenu ! Dauphine accueille beaucoup d'\u00e9tudiants ais\u00e9s, mais pas seulement. Les populations \u00e9tudiantes des d\u00e9partements MIDO et LSO semblent peu diff\u00e9rentes du point de vue de la distribution des revenus, comme le sugg\u00e8rent les donn\u00e9es des cat\u00e9gories socio-professionnelles des parents r\u00e9colt\u00e9es au moment de l'inscription. De fait, le syst\u00e8me modul\u00e9 utilis\u00e9 d\u00e9sormais par le d\u00e9partement LSO est plus juste et plus redistributif que celui utilis\u00e9 par le d\u00e9partement MIDO, et rapporte plus \u00e0 l'universit\u00e9, alors m\u00eame que l'immense majorit\u00e9 des personnels du d\u00e9partement MIDO souhaite la justice sociale. Le paradoxe est manifeste. Si la question cach\u00e9e est de savoir si telle ou telle sous cat\u00e9gorie de la classe moyenne est plus pressur\u00e9e que les autres, la r\u00e9ponse est encore une fois dans la modulation, dont la mise en place peut tenir compte de la distribution des revenus. Ind\u00e9pendamment de ce que pourrait d\u00e9cider le d\u00e9partement MIDO, il est probable qu'au fil des ans le manque d'engagement de l'\u00e9tat entra\u00eene une augmentation de la recette globale des frais d'inscription afin de maintenir les conditions de travail et d'\u00e9tude. Il est \u00e9videmment pr\u00e9f\u00e9rable de vivre cette augmentation probable avec des frais modul\u00e9s plut\u00f4t qu'avec des frais binaires. Le contr\u00f4le des flux g\u00e9n\u00e9r\u00e9s devient en tout cas tr\u00e8s politique, sur fond de diff\u00e9rences de pratiques budg\u00e9taires notables entre disciplines. Ces flux nouveaux pourraient \u00eatre utilis\u00e9s en partie pour renforcer le syst\u00e8me d'aide aux \u00e9tudiants, en tenant compte \u00e0 la fois du social et du m\u00e9rite.<\/p>\n<p style=\"text-align: justify;\">\u00c0 titre personnel, j'appr\u00e9cie plus que toute autre l'universit\u00e9 Paris-Dauphine, unique en France, entre grande \u00e9cole et universit\u00e9, entre professionnalisation et recherche de pointe. La s\u00e9lection est une bonne chose car elle donne de la valeur aux dipl\u00f4mes. La modulation des frais est une bonne chose car elle est socialement juste. Il serait d\u00e9solant que Paris-Dauphine finisse par revenir au standard universitaire fran\u00e7ais \u00e0 bout de souffle, par conformisme, dogmatisme, nostalgie, ou d\u00e9magogie, en faisant l'\u00e9conomie d'une mise \u00e0 plat interne de ses pratiques budg\u00e9taires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce petit billet regroupe quelques libres pens&eacute;es personnelles &eacute;parses sur les droits ou frais d'inscription en licence &agrave; l'universit&eacute; en France. En France, le dipl&ocirc;me&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/djalil.chafai.net\/blog\/2016\/10\/19\/reflexions-sur-les-frais-dinscription-en-licence-a-luniversite\/\">Continue reading<span class=\"screen-reader-text\">R\u00e9flexions sur les frais d&#039;inscription en licence \u00e0 l&#039;universit\u00e9<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":128},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts\/9043"}],"collection":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/comments?post=9043"}],"version-history":[{"count":76,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts\/9043\/revisions"}],"predecessor-version":[{"id":12421,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts\/9043\/revisions\/12421"}],"wp:attachment":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/media?parent=9043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/categories?post=9043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/tags?post=9043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}