{"id":14350,"date":"2020-11-24T15:21:48","date_gmt":"2020-11-24T14:21:48","guid":{"rendered":"http:\/\/djalil.chafai.net\/blog\/?p=14350"},"modified":"2021-03-15T15:51:48","modified_gmt":"2021-03-15T14:51:48","slug":"libres-pensees-sur-la-modelisation-et-lanalyse-quantitative","status":"publish","type":"post","link":"https:\/\/djalil.chafai.net\/blog\/2020\/11\/24\/libres-pensees-sur-la-modelisation-et-lanalyse-quantitative\/","title":{"rendered":"Mod\u00e9lisation et analyse quantitative"},"content":{"rendered":"<figure id=\"attachment_7571\" aria-describedby=\"caption-attachment-7571\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2014\/08\/Unknown_French_Master_-_Allegory_of_the_Vanity_of_Earthly_Things.jpg\"><img loading=\"lazy\" class=\"wp-image-7571 size-medium\" src=\"http:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2014\/08\/Unknown_French_Master_-_Allegory_of_the_Vanity_of_Earthly_Things-300x208.jpg\" alt=\"Allegory of the Vanity of Earthly Things\" width=\"300\" height=\"208\" srcset=\"https:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2014\/08\/Unknown_French_Master_-_Allegory_of_the_Vanity_of_Earthly_Things-300x208.jpg 300w, https:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2014\/08\/Unknown_French_Master_-_Allegory_of_the_Vanity_of_Earthly_Things.jpg 1007w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-7571\" class=\"wp-caption-text\">Allegory of the Vanity of Earthly Things<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ce billet est une version longue et en fran\u00e7ais d'<a href=\"https:\/\/djalil.chafai.net\/blog\/2020\/05\/17\/modelling\/\">un billet pr\u00e9c\u00e9dent publi\u00e9 en anglais au printemps dernier<\/a>. Il s'agit d'une contribution au livre collectif pluridisciplinaire \u00ab <a href=\"https:\/\/dauphine.psl.eu\/dauphine\/media-et-communication\/article\/parution-du-nouvel-ouvrage-covid-19-regards-croises-sur-la-crise\"><em>Covid-19 : regards crois\u00e9s sur la crise<\/em><\/a>\u00a0\u00bb en cours de pr\u00e9paration \u00e0 l'universit\u00e9 Paris-Dauphine. Le texte fait un peu plus de 10 000 caract\u00e8res et le r\u00e9sum\u00e9 environ 1000 caract\u00e8res, espaces compris.<\/p>\n<p style=\"text-align: justify;\"><strong>R\u00e9sum\u00e9.<\/strong><em> La pand\u00e9mie de coronavirus actuelle et sa gestion sont des sujets d'\u00e9tude int\u00e9ressants \u00e0 bien des \u00e9gards. Si l'on se penche sur l'histoire r\u00e9cente et moins r\u00e9cente, cette pand\u00e9mie en elle-m\u00eame appara\u00eet pour l'instant comme plut\u00f4t ordinaire, alors que les r\u00e9ponses politiques le sont moins. On observe en particulier, au-del\u00e0 de l'aversion au risque et d\u2019un mim\u00e9tisme international, un certain r\u00f4le jou\u00e9 par l'analyse quantitative de risque pour la d\u00e9cision, bas\u00e9e sur la mod\u00e9lisation en \u00e9pid\u00e9miologie. Ce texte regroupe des libres pens\u00e9es sur ce qu\u2019est la mod\u00e9lisation math\u00e9matique ou informatique, ce qu\u2019elle n\u2019est pas, le r\u00f4le qu\u2019elle a, qu\u2019elle a eu, et qu\u2019elle pourrait avoir. Le propos est d\u2019apporter un contrepoint critique et historique aux tentations utilitaristes qui sous-tendent la mod\u00e9lisation et l\u2019analyse quantitative, exacerb\u00e9es par la crise du coronavirus que nous vivons.<\/em><\/p>\n<p style=\"text-align: center;\"><b>-<\/b><\/p>\n<p style=\"text-align: justify;\">La mod\u00e9lisation math\u00e9matique r\u00e9ussit remarquablement \u00e0 pr\u00e9dire, avec un haut degr\u00e9 de pr\u00e9cision, le comportement de nombreux ph\u00e9nom\u00e8nes naturels, comme par exemple, et tr\u00e8s concr\u00e8tement, la trajectoire des satellites ou la propagation du son et de la lumi\u00e8re. La mod\u00e9lisation math\u00e9matique joue ind\u00e9niablement un r\u00f4le cl\u00e9 dans la plupart des champs technologiques actuels, souvent \u00e0 travers la physique et l\u2019informatique. Ses nombreux succ\u00e8s ont un impact consid\u00e9rable, concret et positif, sur notre vie quotidienne. Comment expliquer un tel succ\u00e8s de la math\u00e9matisation du monde ? Quelle est la nature du lien entre math\u00e9matiques et monde physique ? Ces questions occupent les penseurs depuis l\u2019antiquit\u00e9. Les plus grands esprits s\u2019y attardent, comme le prix Nobel de physique <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Eugene_Wigner\">Eugene Wigner<\/a>, et son c\u00e9l\u00e8bre \u00ab <em><a href=\"https:\/\/doi.org\/10.1002%2Fcpa.3160130102\">The unreasonable effectiveness of mathematics in the natural sciences<\/a><\/em> \u00bb publi\u00e9 en 1960, ou le grand math\u00e9maticien et informaticien <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Richard_Hamming\">Richard Hamming<\/a>, et son \u00ab <a href=\"https:\/\/doi.org\/10.2307\/2321982\"><em>The unreasonable effectiveness of mathematics<\/em><\/a> \u00bb publi\u00e9 en 1980. Sans vraiment apporter de r\u00e9ponse sur le fond, ces articles dessinent les contours d\u2019une fascinante r\u00e9ussite, qui passe par une quantification et une m\u00e9canisation des ph\u00e9nom\u00e8nes naturels.<\/p>\n<p style=\"text-align: justify;\">D\u2019un autre c\u00f4t\u00e9, il se trouve que les m\u00e9canismes de nombreux ph\u00e9nom\u00e8nes naturels quantifiables ne sont pas bien compris, et m\u00eame lorsqu'ils sont bien compris \u00e0 une certaine \u00e9chelle, leur mod\u00e9lisation math\u00e9matique n\u2019est en g\u00e9n\u00e9ral qu\u2019une approximation parfois grossi\u00e8re de leur complexit\u00e9 et subtilit\u00e9, qui peut beaucoup manquer de pr\u00e9cision. L'approximation peut \u00e9galement provenir de l'analyse math\u00e9matique et num\u00e9rique du mod\u00e8le en lui-m\u00eame, ainsi que du manque de donn\u00e9es pour l'ajuster. Tous ces aspects sont bien connus des math\u00e9maticiens, qui ont coutume de dire que tous les mod\u00e8les sont faux, mais que certains sont utiles. Ces limitations de la mod\u00e9lisation math\u00e9matique des ph\u00e9nom\u00e8nes naturels, li\u00e9es au caract\u00e8re simpliste voire caricatural de la math\u00e9matisation et num\u00e9risation du monde, font contrepoint. L\u2019ing\u00e9nieur <a href=\"https:\/\/en.wikipedia.org\/wiki\/Derek_Abbott\">Derek Abbott<\/a> a publi\u00e9 en 2013 un article remarqu\u00e9 sur ce sujet, intitul\u00e9 \u00ab <em><a href=\"https:\/\/doi.org\/10.1109\/JPROC.2013.2274907\">The reasonable ineffectiveness of mathematics<\/a><\/em> \u00bb, une sorte de pied de nez \u00e0 l\u2019arrogance de ceux d\u2019Eug\u00e8ne Wigner et Richard Hamming.<\/p>\n<p style=\"text-align: justify;\">Le cas de la m\u00e9t\u00e9orologie est particuli\u00e8rement int\u00e9ressant. Les m\u00e9canismes des ph\u00e9nom\u00e8nes naturels sous-jacents sont relativement bien compris et sont mod\u00e9lis\u00e9s math\u00e9matiquement notamment par les \u00e9quations de la m\u00e9canique des fluides, li\u00e9es \u00e0 l'une des plus grandes questions de physique math\u00e9matique. Malheureusement, la sensibilit\u00e9 de ces \u00e9quations aux perturbations rend la pr\u00e9diction relativement limit\u00e9e, malgr\u00e9 les progr\u00e8s remarquables r\u00e9alis\u00e9s dans l'analyse num\u00e9rique et la puissance de calcul, et malgr\u00e9 l'\u00e9norme quantit\u00e9 de donn\u00e9es collect\u00e9es par t\u00e9l\u00e9d\u00e9tection par satellite. Les pr\u00e9visions m\u00e9t\u00e9orologiques \u00e0 moyen\/long terme restent inaccessibles.<\/p>\n<p style=\"text-align: justify;\">La situation est pire encore pour les sciences sociales comme l'\u00e9conomie ou la sociologie, pour lesquelles nous n'avons pas l'analogue des \u00e9quations de la m\u00e9canique des fluides. Historiquement, l'analyse quantitative des ph\u00e9nom\u00e8nes sociaux a d'abord \u00e9t\u00e9 abord\u00e9e \u00e0 l'aide de donn\u00e9es statistiques, notamment par <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Adolphe_Quetelet\">Adolphe Quetelet<\/a>, qui a produit entre autres \u00e9tudes son c\u00e9l\u00e8bre \u00ab <em>Sur l'homme et le d\u00e9veloppement de ses facult\u00e9s, ou Essai de physique sociale<\/em> \u00bb (1835). Quetelet a d\u00e9couvert une m\u00e9canique, une r\u00e9gularit\u00e9 des ph\u00e9nom\u00e8nes al\u00e9atoires, ouvrant la voie \u00e0 la mod\u00e9lisation math\u00e9matique des syst\u00e8mes d\u00e9sordonn\u00e9s et \u00e0 leur pr\u00e9visibilit\u00e9. L\u2019id\u00e9e fondamentale est que ce sont les distributions statistiques ou les lois de probabilit\u00e9s qui sont justiciables d\u2019une m\u00e9canique et d\u2019une pr\u00e9diction, et non pas les ph\u00e9nom\u00e8nes al\u00e9atoires au niveau individuel. Cette distinction entre comportement microscopique ou individuel et comportement macroscopique ou de population pose \u00e9galement le probl\u00e8me philosophique du libre arbitre. Adolphe Quetelet, h\u00e9ritier de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Pierre-Simon_de_Laplace\">Pierre-Simon de Laplace<\/a>, n'\u00e9tait pas le seul scientifique du dix-neuvi\u00e8me si\u00e8cle \u00e0 explorer une vision m\u00e9caniste de la nature, les plus c\u00e9l\u00e8bres \u00e9tant peut-\u00eatre <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Charles_Darwin\">Charles Darwin<\/a> et <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ludwig_Boltzmann\">Ludwig Boltzmann<\/a>, dont les id\u00e9es r\u00e9volutionnaires ont \u00e9t\u00e9 longtemps fort controvers\u00e9es avant d\u2019\u00eatre int\u00e9gr\u00e9es dans le corpus scientifique. La m\u00e9canisation des syst\u00e8mes d\u00e9sordonn\u00e9s amorc\u00e9e \u00e0 l\u2019\u00e9poque a conduit aux grands succ\u00e8s de la th\u00e9orie des probabilit\u00e9s et de la statistique que nous connaissons tous aujourd\u2019hui, qui sont \u00e9galement au c\u0153ur de la physique statistique, de la m\u00e9canique quantique, et de la th\u00e9orie de l'information. Mais les sciences sociales restent malgr\u00e9 tout bien trop complexes pour de nombreux aspects. Les limitations de la mod\u00e9lisation pour l\u2019\u00e9conomie mais aussi la difficult\u00e9 de l\u2019analyse des donn\u00e9es sont abord\u00e9es par exemple par <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Thomas_Piketty\">Thomas Piketty<\/a> dans \u00ab <em>Le Capital au XXIe si\u00e8cle<\/em> \u00bb (Seuil, 2013).<\/p>\n<p style=\"text-align: justify;\">Le formidable d\u00e9veloppement de la num\u00e9risation, des ordinateurs, des bases de donn\u00e9es massives, et des r\u00e9seaux a conduit \u00e0 une utilisation g\u00e9n\u00e9ralis\u00e9e de la mod\u00e9lisation et des algorithmes, bien au-del\u00e0 des p\u00e9rim\u00e8tres habituels. Cela a \u00e9galement stimul\u00e9 le d\u00e9veloppement de divers types d'apprentissage automatique, produisant des succ\u00e8s parfois \u00e9tonnants dont on ne comprend pas forc\u00e9ment les tenants et les aboutissants. Ce type de traitement algorithmique des donn\u00e9es est toujours consid\u00e9r\u00e9 comme de la mod\u00e9lisation mais peut diff\u00e9rer de la mod\u00e9lisation habituelle en ce qu'il peut produire des pr\u00e9dictions empiriques sans compr\u00e9hension.<\/p>\n<p style=\"text-align: justify;\">Qu\u2019en est-il de l'\u00e9pid\u00e9miologie ? Il s'av\u00e8re que les m\u00e9canismes biologiques et m\u00e9dicaux des \u00e9pid\u00e9mies virales ne sont pas bien compris par les scientifiques pour l'instant, m\u00eame si la science progresse \u00e0 l\u2019occasion de chaque \u00e9pid\u00e9mie. La mod\u00e9lisation math\u00e9matique ou informatique d\u00e9velopp\u00e9e en \u00e9pid\u00e9miologie incorpore au mieux ce qui est connu. Elle reste cependant limit\u00e9e pour la pr\u00e9diction, et le probl\u00e8me ne se r\u00e9duit pas \u00e0 la collecte de donn\u00e9es, \u00e0 la sensibilit\u00e9 des mod\u00e8les, ou \u00e0 la complexit\u00e9 des ph\u00e9nom\u00e8nes. En particulier, cela produit une analyse des risques discutable pour la prise de d\u00e9cision. On pourrait alternativement utiliser les statistiques historiques des \u00e9pid\u00e9mies pour produire des pr\u00e9dictions, au moins de nature qualitative ou ph\u00e9nom\u00e9nologique, mais cela est \u00e9galement relativement limit\u00e9. Nous sommes donc condamn\u00e9s \u00e0 vivre pour l'instant avec d'importantes incertitudes. C'est quelque peu difficile \u00e0 accepter pour nos soci\u00e9t\u00e9s actuelles, dont l\u2019aversion au risque est importante, et dont le rapport \u00e0 la fin de vie est boulevers\u00e9.<\/p>\n<p style=\"text-align: justify;\">La mod\u00e9lisation en \u00e9pid\u00e9miologie n\u2019en demeure pas moins int\u00e9ressante pour explorer les ph\u00e9nom\u00e8nes, les hypoth\u00e8ses, faire avancer notre compr\u00e9hension des m\u00e9canismes et de leurs effets. La mod\u00e9lisation permet \u00e9galement la conception d\u2019indicateurs quantitatifs avanc\u00e9s et l\u2019organisation g\u00e9n\u00e9rale des moyens. La controverse fait partie de la science, mais le temps d\u2019\u00e9laboration de la science reste cependant bien diff\u00e9rent du temps de la d\u00e9cision, du temps politique ou m\u00e9diatique.<\/p>\n<p style=\"text-align: justify;\">D\u2019autre part, force est de constater qu\u2019en ces temps d\u2019hypersp\u00e9cialisation, nos scientifiques ne sont plus vraiment philosophes, tandis que nos philosophes ne sont plus vraiment scientifiques. Quant \u00e0 nos d\u00e9cideurs et \u00e0 nos journalistes, ils ne sont bien souvent ni l\u2019un ni l\u2019autre. C\u2019est donc aussi de pluridisciplinarit\u00e9 et de pens\u00e9es crois\u00e9es, autant \u00e0 l\u2019\u00e9chelle individuelle que collective, dont nous avons besoin. Les jeunes esprits y sont r\u00e9ceptifs, et cela peut inspirer et \u00e9toffer nos formations universitaires. On a coutume de dire que l\u2019esprit critique et le sens de l\u2019histoire sont essentiels \u00e0 la science et \u00e0 sa diffusion. \u00c0 la fin du seizi\u00e8me si\u00e8cle, les horoscopes du grand astronome <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Johannes_Kepler\">Johannes Kepler<\/a>, l\u2019un des plus grands scientifiques de tous les temps, \u00e9taient tr\u00e8s pris\u00e9s des puissants qui l\u2019employaient, et Kepler lui-m\u00eame \u00e9tait persuad\u00e9 que l\u2019astrologie pouvait devenir une science au m\u00eame titre que l\u2019astronomie. Certaines des pr\u00e9dictions astrologiques de Kepler se sont r\u00e9v\u00e9l\u00e9es exactes. L\u2019aventure scientifique depuis cette \u00e9poque incite les scientifiques \u00e0 la prudence et \u00e0 l\u2019humilit\u00e9, \u00e0 ne pas devenir de simples marchands de certitudes au service des puissants. Servir des sc\u00e9narios issus de mod\u00e9lisations approximatives ne risque-t-il pas d\u2019alimenter la peur ou l\u2019insouciance, de produire des exc\u00e8s regrettables y compris pour la science ?<\/p>\n<p style=\"text-align: justify;\">Toujours \u00e0 propos d\u2019histoire, et concernant la pand\u00e9mie de coronavirus du printemps 2020 en France, examinons le graphique de l\u2019INSEE qui superpose les courbes de mortalit\u00e9 totale de p\u00e9riodes pass\u00e9es marquantes, notamment la canicule de l\u2019\u00e9t\u00e9 2003, des grippes saisonni\u00e8res des ann\u00e9es r\u00e9centes, et la grippe dite de Hong Kong, qui a frapp\u00e9 la France \u00e0 l\u2019hiver 1969-1970 dans une quasi-indiff\u00e9rence g\u00e9n\u00e9rale. La chose la plus frappante est peut-\u00eatre la similarit\u00e9 en forme et en taille entre le pic de cette grippe de Hong Kong et celui de l\u2019\u00e9pid\u00e9mie de coronavirus du printemps 2020. En 2020, un confinement de la population a \u00e9t\u00e9 organis\u00e9, par mim\u00e9tisme international et au vu des pr\u00e9dictions issues de mod\u00e9lisations en \u00e9pid\u00e9miologie. Comment en \u00e9valuer l\u2019efficacit\u00e9 globale et la pertinence ? La d\u00e9marche scientifique est assez limit\u00e9e car il n\u2019est pas possible de r\u00e9p\u00e9ter l\u2019exp\u00e9rience en contr\u00f4lant les param\u00e8tres. L\u2019effet sur les accidents de la route, souvent \u00e9voqu\u00e9, est bien r\u00e9el mais une simple r\u00e8gle de trois r\u00e9v\u00e8le que cela ne change pas \u00e9norm\u00e9ment les choses quantitativement. La m\u00e9decine a certainement \u00e9volu\u00e9 entre les deux \u00e9poques. D\u2019autre part, la population fran\u00e7aise en 1969-1970 \u00e9tait bien plus petite et bien plus jeune qu\u2019en 2020. L\u2019essentiel des d\u00e9c\u00e8s en question concerne les personnes \u00e2g\u00e9es, pour partie en \u00e9tablissement sp\u00e9cialis\u00e9. Notons \u00e9galement que la grippe dite espagnole en fin de premi\u00e8re guerre mondiale \u2013 absente du graphique \u2013 a plut\u00f4t tu\u00e9 les jeunes adultes, par surinfection bact\u00e9rienne, avant l\u2019\u00e8re des antibiotiques. Tout cela souligne aussi bien la tentation et la difficult\u00e9 \u00e0 comparer \u00e0 travers le temps. Une analyse du m\u00eame type pourrait aussi \u00eatre men\u00e9e \u00e0 travers l\u2019espace. Ces ph\u00e9nom\u00e8nes extr\u00eames et r\u00e9currents sont encore plus complexes et h\u00e9t\u00e9rog\u00e8nes que les crues des fleuves dont les bassins \u00e9voluent. Il s\u2019agit l\u00e0 d\u2019un probl\u00e8me majeur de l\u2019analyse de donn\u00e9es \u00e0 travers le temps et l\u2019espace. La principale difficult\u00e9 \u00e0 laquelle est confront\u00e9 Thomas Piketty dans son travail sur le capital est pr\u00e9cis\u00e9ment l\u2019h\u00e9t\u00e9rog\u00e9n\u00e9it\u00e9 spatio-temporelle des donn\u00e9es statistiques concernant l\u2019\u00e9conomie.<\/p>\n<figure id=\"attachment_14353\" aria-describedby=\"caption-attachment-14353\" style=\"width: 1030px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2020\/11\/Chafai-Djalil-Figure-1.png\"><img loading=\"lazy\" class=\"size-large wp-image-14353\" src=\"http:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2020\/11\/Chafai-Djalil-Figure-1-1030x640.png\" alt=\"Mortalit\u00e9 compar\u00e9e\" width=\"1030\" height=\"640\" srcset=\"https:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2020\/11\/Chafai-Djalil-Figure-1-1030x640.png 1030w, https:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2020\/11\/Chafai-Djalil-Figure-1-300x187.png 300w, https:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2020\/11\/Chafai-Djalil-Figure-1-768x478.png 768w, https:\/\/djalil.chafai.net\/blog\/wp-content\/uploads\/2020\/11\/Chafai-Djalil-Figure-1.png 1462w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><figcaption id=\"caption-attachment-14353\" class=\"wp-caption-text\">Mortalit\u00e9 compar\u00e9e. Superposition des courbes de d\u00e9c\u00e8s, en France, tout le long de l\u2018ann\u00e9e, pour chaque ann\u00e9e depuis 2010, ainsi que pour certaines ann\u00e9es exceptionnelles plus lointaines dans le pass\u00e9. Le grand pic en jaune, au milieu, est celui de la canicule de l\u2019\u00e9t\u00e9 2003, accompagn\u00e9 de plusieurs petits pics des canicules d\u2018autres \u00e9t\u00e9s. Le grand pic rouge \u00e0 gauche est celui de l\u2018\u00e9pid\u00e9mie du coronavirus du printemps 2020. Le grand pic bleu, essentiellement \u00e0 droite, est celui de la grippe dite de Hong Kong de l\u2019hiver 1969-1970, environn\u00e9 de plusieurs petits pics des grippes d\u2018autres hivers. Source : <a href=\"https:\/\/blog.insee.fr\/statistiques-sur-les-deces-le-mode-demploi-des-donnees-de-linsee-en-7-questions-reponses\/\">Statistiques sur les d\u00e9c\u00e8s : le mode d\u2019emploi des donn\u00e9es de l\u2019Insee en 7 questions\/r\u00e9ponses<\/a>, blog de l\u2019<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Institut_national_de_la_statistique_et_des_%C3%A9tudes_%C3%A9conomiques\">INSEE<\/a>.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce billet est une version longue et en fran&ccedil;ais d'un billet pr&eacute;c&eacute;dent publi&eacute; en anglais au printemps dernier. Il s'agit d'une contribution au livre collectif&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/djalil.chafai.net\/blog\/2020\/11\/24\/libres-pensees-sur-la-modelisation-et-lanalyse-quantitative\/\">Continue reading<span class=\"screen-reader-text\">Mod\u00e9lisation et analyse quantitative<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":250},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts\/14350"}],"collection":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/comments?post=14350"}],"version-history":[{"count":17,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts\/14350\/revisions"}],"predecessor-version":[{"id":14863,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/posts\/14350\/revisions\/14863"}],"wp:attachment":[{"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/media?parent=14350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/categories?post=14350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/djalil.chafai.net\/blog\/wp-json\/wp\/v2\/tags?post=14350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}